{"id":146507,"date":"2024-03-21T06:00:00","date_gmt":"2024-03-21T05:00:00","guid":{"rendered":"https:\/\/lexpress-franchise.com\/fr-be\/articles\/se-lancer-en-franchise-pour-rebondir\/"},"modified":"2024-07-17T09:30:38","modified_gmt":"2024-07-17T07:30:38","slug":"se-lancer-en-franchise-pour-rebondir","status":"publish","type":"post","link":"https:\/\/lexpress-franchise.com\/fr-be\/articles\/se-lancer-en-franchise-pour-rebondir\/","title":{"rendered":"Se lancer en franchise pour rebondir"},"content":{"rendered":"\n<p><strong>Longtemps salari\u00e9s, leur parcours a connu un revers lors d\u2019un plan \u00e9conomique. Pour rebondir, la franchise est apparue comme la solution la plus adapt\u00e9e \u00e0 leurs besoins.<\/strong><\/p>\n\n<hr class=\"wp-block-separator has-text-color has-lexpress-rouge-1-color has-alpha-channel-opacity has-lexpress-rouge-1-background-color has-background is-style-dots\" \/>\n\n<p>Apr\u00e8s vingt-cinq ans de carri\u00e8re chez Stellantis (ex-PSA), Isabelle Dewimille se voit proposer d\u2019int\u00e9grer un plan de d\u00e9parts volontaires. Elle accepte la proposition de son employeur et en profite pour r\u00e9aliser un bilan de comp\u00e9tences. \u00ab Cela m\u2019a confort\u00e9e dans l\u2019id\u00e9e d\u2019\u00e9voluer dans un poste diff\u00e9rent, plus ax\u00e9 sur le sanitaire et social ou la formation et transmission \u00bb, confie-t-elle. De fil en aiguille, Isabelle Dewimille d\u00e9couvre le r\u00e9seau de franchise Apef, sp\u00e9cialiste des services \u00e0 la personne. \u00ab Une reconversion dans cette branche r\u00e9pondait \u00e0 mes envies de faire du management humain et de travailler dans un secteur tourn\u00e9 sur le service \u00bb. Elle ouvre son agence en avril 2023, sur la ville de Belfort. Elle finance les droits d\u2019entr\u00e9e gr\u00e2ce \u00e0 sa prime de d\u00e9part et pr\u00e9voit aussi ses premiers salaires, n\u2019\u00e9tant pas s\u00fbre de pouvoir se r\u00e9mun\u00e9rer dans l\u2019imm\u00e9diat. \u00ab <a href=\"https:\/\/lexpress-franchise.com\/articles\/reconversion-et-quete-de-sens-quand-les-femmes-misent-sur-lentrepreneuriat-en-franchise\/\" target=\"_blank\" rel=\"noreferrer noopener\"> L\u2019aspect s\u00e9curisant de la franchise m\u2019est apparu comme une \u00e9vidence<\/a> \u00bb, poursuit l\u2019entrepreneure.<\/p>\n\n<h2 class=\"wp-block-heading has-lexpress-rouge-1-color has-text-color has-link-color wp-elements-3f0e642b61e465550d28569347ff5ddf\">Rebondir : l\u2019importance du bon feeling<\/h2>\n\n<p>S\u00e9curisant, le mot est sur toutes les l\u00e8vres des salari\u00e9s s\u00e9duits par la franchise. \u00ab Ce mod\u00e8le correspond bien aux besoins de ceux qui ont connu un plan de d\u00e9part volontaire, abonde Serge Voiry, conseiller en ressources humaines. Ce genre d\u2019\u00e9v\u00e9nement conduit les personnes concern\u00e9es \u00e0 penser d\u2019abord en mode \u00ab projet \u00bb, celui <a href=\"https:\/\/lexpress-franchise.com\/articles\/javais-envie-detre-mon-propre-patron-rencontre-avec-nicolas-petitperrin-et-audrey-colinet-franchises-jordan-tomas-pizzas-m\/\" target=\"_blank\" rel=\"noreferrer noopener\">d\u2019\u00eatre son propre patron<\/a> et de se tourner vers un certain type de secteur. Avec la franchise, elles gagnent du temps en b\u00e9n\u00e9ficiant d\u2019embl\u00e9e d\u2019un produit, d\u2019un accompagnement et d\u2019un r\u00e9seau. \u00bb Cette solution appara\u00eet donc moins risqu\u00e9e que la cr\u00e9ation pure et simple d\u2019entreprise. \u00ab Elle est aussi une r\u00e9action au monde salarial : je veux \u00eatre autonome, ind\u00e9pendant \u00bb, glisse Serge Voiry.<\/p>\n\n<p>C\u2019est d\u2019ailleurs ce qui a convaincu cet ancien collaborateur du secteur financier d\u2019ouvrir son agence Prelys Courtage : \u00ab J\u2019avais d\u00e9couvert <a href=\"https:\/\/lexpress-franchise.com\/articles\/courtiers-professionnels-un-metier-en-plein-essor\/\" target=\"_blank\" rel=\"noreferrer noopener\">le courtage<\/a> lors d\u2019une demande de pr\u00eat immobilier. Je me suis rendu compte qu\u2019il y avait beaucoup \u00e0 faire d\u2019un point de vue commercial dans ce secteur \u00bb. Pour lui, apr\u00e8s avoir v\u00e9cu la violence d\u2019un licenciement \u00e9conomique, plus question d\u2019\u00eatre salari\u00e9. Pas question non plus de se lancer seul dans l\u2019entrepreneuriat quand on manque de connaissances dans le domaine des pr\u00eats immobiliers. Le risque \u00e9tait trop grand. Ce candidat \u00e0 la franchise a b\u00e9n\u00e9fici\u00e9 d\u2019une formation et d\u2019un temps de soutien hebdomadaire puis mensuel la premi\u00e8re ann\u00e9e d\u2019exercice.<\/p>\n\n<h2 class=\"wp-block-heading has-lexpress-rouge-1-color has-text-color has-link-color wp-elements-4703ca2e3e79af8490b7b44e235627d2\">La franchise : ouvrir une entreprise en toute confiance<\/h2>\n\n<p>Souvent, les anciens salari\u00e9s ont besoin d\u2019un soutien qui leur redonne confiance. \u00ab Ils appr\u00e9cieront de r\u00e9int\u00e9grer une marque ou une entreprise, non plus sur le m\u00eame positionnement, en tant que salari\u00e9 mais en tant que responsable d\u2019une organisation, commente Serge Voiry. Toutefois attention, il y a aussi un processus \u00e0 respecter et, dans certains cas, des r\u00e9seaux qui laissent moins d\u2019autonomie. \u00bb Et c\u2019est d\u2019ailleurs en fonction de ses attentes et de ses envies de cr\u00e9ativit\u00e9 qu\u2019il faut choisir son franchiseur.<\/p>\n\n<p>Ainsi, Elian Condomines, ex-salari\u00e9 dans le n\u00e9goce de produits pour le b\u00e2timent, choisit de rebondir aupr\u00e8s de <a href=\"https:\/\/lexpress-franchise.com\/franchise\/fhv-ventilation\/\" target=\"_blank\" rel=\"noreferrer noopener\">France Hygi\u00e8ne Ventilation<\/a>, une toute jeune structure cr\u00e9\u00e9e en 2016. \u00ab Je recherchais une franchise B to B, o\u00f9 je pouvais conserver une certaine libert\u00e9, explique-t-il. Avec une franchise install\u00e9e, il faudra accepter d\u2019apprendre beaucoup, de s\u2019y conformer et d\u2019avoir moins d\u2019influence sur son organisation. \u00bb La cerise sur le g\u00e2teau ? Cette reconversion lui a permis d\u2019ouvrir son agence en Is\u00e8re, r\u00e9pondant ainsi \u00e0 son souhait de ruralit\u00e9. Le salariat c\u2019en \u00e9tait fini, la ville aussi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Longtemps salari\u00e9s, leur parcours a connu un revers lors d\u2019un plan \u00e9conomique. Pour rebondir, la franchise est apparue comme la solution la plus adapt\u00e9e \u00e0 leurs besoins. Apr\u00e8s vingt-cinq ans de carri\u00e8re chez Stellantis (ex-PSA), Isabelle Dewimille se voit proposer d\u2019int\u00e9grer un plan de d\u00e9parts volontaires. Elle accepte la proposition de son employeur et en [&hellip;]<\/p>\n","protected":false},"author":138,"featured_media":108995,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"none","_seopress_titles_title":"Se lancer en franchise pour rebondir","_seopress_titles_desc":"Salari\u00e9s pendant de nombreuses ann\u00e9es, leur parcours a connu un revers lors d\u2019un plan \u00e9conomique.La franchise est apparue comme la solution pour rebondir.","_seopress_robots_index":"yes","content-type":"","_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"16991,24778,10156,9579,83719,5459","_relevanssi_noindex_reason":"","footnotes":""},"categories":[846,1375,54],"tags":[],"type-de-post":[438],"class_list":{"0":"post-146507","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-histoire-dentrepreneurs","8":"category-inspirations","9":"category-se-lancer","10":"type-de-post-articles"},"acf":[],"_links":{"self":[{"href":"https:\/\/lexpress-franchise.com\/fr-be\/wp-json\/wp\/v2\/posts\/146507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lexpress-franchise.com\/fr-be\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lexpress-franchise.com\/fr-be\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lexpress-franchise.com\/fr-be\/wp-json\/wp\/v2\/users\/138"}],"replies":[{"embeddable":true,"href":"https:\/\/lexpress-franchise.com\/fr-be\/wp-json\/wp\/v2\/comments?post=146507"}],"version-history":[{"count":0,"href":"https:\/\/lexpress-franchise.com\/fr-be\/wp-json\/wp\/v2\/posts\/146507\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lexpress-franchise.com\/fr-be\/wp-json\/wp\/v2\/media\/108995"}],"wp:attachment":[{"href":"https:\/\/lexpress-franchise.com\/fr-be\/wp-json\/wp\/v2\/media?parent=146507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lexpress-franchise.com\/fr-be\/wp-json\/wp\/v2\/categories?post=146507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lexpress-franchise.com\/fr-be\/wp-json\/wp\/v2\/tags?post=146507"},{"taxonomy":"type-de-post","embeddable":true,"href":"https:\/\/lexpress-franchise.com\/fr-be\/wp-json\/wp\/v2\/type-de-post?post=146507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}