{"id":1528838,"date":"2026-02-06T06:00:00","date_gmt":"2026-02-06T05:00:00","guid":{"rendered":"https:\/\/lexpress-franchise.com\/es\/ultimas-noticias\/la-marca-de-ecografias-emocionales-ecox-preve-abrir-hasta-40-nuevos-centros-en-3-anos\/"},"modified":"2026-05-15T15:17:22","modified_gmt":"2026-05-15T13:17:22","slug":"la-marca-de-ecografias-emocionales-ecox-preve-abrir-hasta-40-nuevos-centros-en-3-anos","status":"publish","type":"post","link":"https:\/\/lexpress-franchise.com\/es\/ultimas-noticias\/la-marca-de-ecografias-emocionales-ecox-preve-abrir-hasta-40-nuevos-centros-en-3-anos\/","title":{"rendered":"La marca de ecograf\u00edas emocionales ecox prev\u00e9 abrir hasta 40 nuevos centros en 3 a\u00f1os"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>En esta entrevista, Abelardo Mart\u00ednez, responsable de expansi\u00f3n de ecox, nos cuenta <a href=\"https:\/\/lexpress-franchise.com\/es\/noticias\/redes-de-franquicias\/\">c\u00f3mo funciona la red de franquicias<\/a> de ecograf\u00edas emocionales, las ventajas para los franquiciados y su estrategia de crecimiento en Espa\u00f1a para los pr\u00f3ximos a\u00f1os. Ecox combina tecnolog\u00eda avanzada, formaci\u00f3n completa y un modelo probado de negocio con alta rentabilidad.<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\"\/>\n\n\n\n<h2 class=\"wp-block-heading has-primary-color has-text-color has-link-color wp-elements-c3499b832f58f71b1106ff57fd73d3e0\">\u00bfQu\u00e9 es ecox?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La empresa ecox es un negocio y red de franquicias <strong>especializada en ecograf\u00edas emocionales prenatales en 3D, 4D y 5D<\/strong>, que permite a futuros padres ver im\u00e1genes detalladas y en movimiento de su beb\u00e9 durante el embarazo con tecnolog\u00eda de alta calidad.<\/p>\n\n\n        <div class=\"lf-gut-franchise-slider-wrapper\" data-slider-id=\"lf-gut-franchise-slider-6a57297d83bda\">\n            <div class=\"lf-gut-franchise-slider swiper\">\n                <div class=\"swiper-wrapper\">\n                                            <div class=\"swiper-slide lf-gut-franchise-card\">\n                            <div class=\"lf-gut-franchise-image-wrapper\">\n                                <img decoding=\"async\" src=\"https:\/\/lexpress-franchise.com\/wp-content\/uploads\/2025\/12\/ecox-6-360x240.png\" class=\"lf-gut-franchise-image\" alt=\"ecox 4D-5D\">\n                                                                    <div class=\"lf-gut-franchise-logo-center\">\n                                        <img decoding=\"async\" src=\"https:\/\/lexpress-franchise.com\/wp-content\/uploads\/2025\/12\/logo-ecox-150x150.png\" alt=\"Logo\">\n                                    <\/div>\n                                                            <\/div>\n                            <div class=\"lf-gut-franchise-content\">\n                                <div class=\"lf-gut-franchise-title-content\">\n                                    <div>\n                                        <p class=\"lf-gut-franchise-title\">ecox 4D-5D<\/p>\n                                        <p class=\"lf-gut-franchise-tag-line\">Ecograf\u00eda emocional a embarazadas<\/p>\n                                    <\/div>\n                                    <ul class=\"lf-gut-franchise-info-list\">\n                                        <li data-field=\"category\">\n                                            <span class=\"lf-gut-icon\"><?xml version=\"1.0\" encoding=\"UTF-8\"?> <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M12.5852 21.9314H4.92807C3.01378 21.9314 2.05664 20.9355 2.05664 18.9438V10.9771C2.05664 8.98542 3.01378 7.98957 4.92807 7.98957M12.5852 21.9314C10.6709 21.9314 9.71378 20.9355 9.71378 18.9438M12.5852 21.9314H18.3281C20.2424 21.9314 21.1995 20.9355 21.1995 18.9438V5.00205C21.1995 3.01037 20.2424 2.01453 18.3281 2.01453H12.5852C10.6709 2.01453 9.71378 3.01037 9.71378 5.00205M4.92807 7.98957H9.71378M4.92807 7.98957V5.99789C4.92807 4.90247 5.7895 4.00621 6.84235 4.00621H9.81905C9.74248 4.30496 9.71378 4.63359 9.71378 5.00205M9.71378 7.98957V18.9438M9.71378 7.98957V5.00205M9.71378 18.9438V5.00205M13.5424 7.98957V12.9688M17.3709 7.98957V12.9688M5.88521 12.9688V16.9521M16.4138 16.9521H14.4995C13.9731 16.9521 13.5424 17.4003 13.5424 17.948V21.9314H17.3709V17.948C17.3709 17.4003 16.9402 16.9521 16.4138 16.9521Z\" stroke=\"#E53B12\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg> <\/span>Bienestar                                        <\/li>\n                                        <li data-field=\"locations\">\n                                            <span class=\"lf-gut-icon\"><?xml version=\"1.0\" encoding=\"UTF-8\"?> <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"19\" height=\"22\" viewBox=\"0 0 19 22\" fill=\"none\"><path d=\"M9.62821 12.2473C11.2775 12.2473 12.6145 10.8563 12.6145 9.14032C12.6145 7.42435 11.2775 6.03329 9.62821 6.03329C7.97893 6.03329 6.64192 7.42435 6.64192 9.14032C6.64192 10.8563 7.97893 12.2473 9.62821 12.2473Z\" stroke=\"#E53B12\" stroke-width=\"1.5\"><\/path><path d=\"M1.60735 7.32788C3.49292 -1.29611 15.7731 -1.28615 17.6491 7.33784C18.7498 12.3967 15.7252 16.6788 13.0739 19.3278C11.1501 21.2597 8.10635 21.2597 6.17292 19.3278C3.53121 16.6788 0.506638 12.3868 1.60735 7.32788Z\" stroke=\"#E53B12\" stroke-width=\"1.5\"><\/path><\/svg> <\/span>64 locales                                        <\/li>\n                                        <li data-field=\"contribution\">\n                                            <span class=\"lf-gut-icon\"><?xml version=\"1.0\" encoding=\"UTF-8\"?> <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"25\" viewBox=\"0 0 24 25\" fill=\"none\"><path d=\"M2.05664 9.19308H21.1995M5.88521 17.1598H7.7995M10.1924 17.1598H14.0209M6.30635 4.21387H16.9402C20.3476 4.21387 21.1995 5.09021 21.1995 8.58561V16.7615C21.1995 20.2569 20.3476 21.1332 16.9498 21.1332H6.30635C2.9085 21.1432 2.05664 20.2668 2.05664 16.7714V8.58561C2.05664 5.09021 2.9085 4.21387 6.30635 4.21387Z\" stroke=\"#E53B12\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg> <\/span>Capital propio: 17.000&nbsp;\u20ac                                        <\/li>\n                                                                            <\/ul>\n                                <\/div>\n                                <a class=\"lf-gut-franchise-button\" rel=\"follow\" href=\"https:\/\/lexpress-franchise.com\/es\/franquicia\/ecox-4d-5d\/?demandedocumentation=1&#038;utm_source=media&#038;utm_medium=1528838&#038;utm_campaign=cta-slider\">\u00a1quiero m\u00e1s informaci\u00f3n!<\/a>\n                            <\/div>\n                        <\/div>\n                                                        <\/div>\n            <\/div>\n            <div class=\"lf-gut-franchise-slider-nav\">\n                <div class=\"swiper-button-prev\"><\/div>\n                <div class=\"swiper-button-next\"><\/div>\n            <\/div>\n        <\/div>\n        \n\n<div class=\"lc-gut-blog-post-interview\" style=\"--color: #e74c3c;\"><div class=\"lc-gut-blog-post-interview__header\"><h2 class=\"lc-gut-blog-post-interview__header-content\"><span class=\"lc-gut-blog-post-interview__number\">10<\/span><div class=\"lc-gut-blog-post-interview__header-text\"><span class=\"lc-gut-blog-post-interview__top-label\">preguntas&nbsp;<\/span><span class=\"lc-gut-blog-post-interview__subtitle\">a Abelardo Mart\u00ednez, responsable de Expansi\u00f3n de ecox<\/span><\/div><\/h2><\/div><div class=\"lc-gut-blog-post-interview__qa\"><div class=\"lc-gut-blog-post-interview__item lc-gut-blog-post-interview__question\"><div class=\"lc-gut-blog-post-interview__person-image-wrap\"><img decoding=\"async\" class=\"lc-gut-blog-post-interview__person-image\" src=\"\/wp-content\/uploads\/2025\/08\/3f55c099cde3bffdfd03be0c9d50584e1a131ba7.png\" alt=\"Question Person\" \/><\/div><div class=\"lc-gut-blog-post-interview__content\"><div class=\"question\"><h3 class=\"lc-gut-blog-post-interview__question\"><strong>\u00bfCu\u00e1l fue el origen de ecox?<\/strong><\/h3><\/div><\/div><\/div><div class=\"lc-gut-blog-post-interview__item lc-gut-blog-post-interview__answer\"><div class=\"lc-gut-blog-post-interview__content\"><div class=\"answer\"><p class=\"lc-gut-blog-post-interview__answer\"><strong>Abelardo Mart\u00ednez<\/strong>:<strong> <\/strong>Generar el <strong>primer v\u00ednculo emocional en el embarazo<\/strong>, para la futura mam\u00e1, su pareja y para todo su entorno, con la mejor tecnolog\u00eda disponible.<\/p><\/div><\/div><\/div><div class=\"lc-gut-blog-post-interview__item lc-gut-blog-post-interview__question\"><div class=\"lc-gut-blog-post-interview__person-image-wrap\"><img decoding=\"async\" class=\"lc-gut-blog-post-interview__person-image\" src=\"\/wp-content\/uploads\/2025\/08\/3f55c099cde3bffdfd03be0c9d50584e1a131ba7.png\" alt=\"Question Person\" \/><\/div><div class=\"lc-gut-blog-post-interview__content\"><div class=\"question\"><h3 class=\"lc-gut-blog-post-interview__question\"><strong>\u00bfPor qu\u00e9  en ecox decidieron apostar por el sistema de franquicias?<\/strong><\/h3><\/div><\/div><\/div><div class=\"lc-gut-blog-post-interview__item lc-gut-blog-post-interview__answer\"><div class=\"lc-gut-blog-post-interview__content\"><div class=\"answer\"><p class=\"lc-gut-blog-post-interview__answer\"><strong>Abelardo Mart\u00ednez<\/strong>: El <a href=\"https:\/\/lexpress-franchise.com\/es\/articulos\/que-es-una-franquicia\/\">sistema de franquicias<\/a> nos permite <strong>crecer estrat\u00e9gicamente<\/strong> con un sistema probado, que funciona.<\/p><\/div><\/div><\/div><div class=\"lc-gut-blog-post-interview__item lc-gut-blog-post-interview__question\"><div class=\"lc-gut-blog-post-interview__person-image-wrap\"><img decoding=\"async\" class=\"lc-gut-blog-post-interview__person-image\" src=\"\/wp-content\/uploads\/2025\/08\/3f55c099cde3bffdfd03be0c9d50584e1a131ba7.png\" alt=\"Question Person\" \/><\/div><div class=\"lc-gut-blog-post-interview__content\"><div class=\"question\"><h3 class=\"lc-gut-blog-post-interview__question\"><strong>\u00bfPor qu\u00e9 para abrir una franquicia ecox no se requiere titulaci\u00f3n previa?<\/strong><\/h3><\/div><\/div><\/div><div class=\"lc-gut-blog-post-interview__item lc-gut-blog-post-interview__answer\"><div class=\"lc-gut-blog-post-interview__content\"><div class=\"answer\"><p class=\"lc-gut-blog-post-interview__answer\"><strong>Abelardo Mart\u00ednez<\/strong>: Para ecox <strong>la formaci\u00f3n es uno de los pilares fundamentales<\/strong>, ecox imparte la formaci\u00f3n con contenidos te\u00f3ricos y pr\u00e1cticos. Contamos con formadores cualificados y se obtiene el t\u00edtulo de T\u00e9cnico en Ecograf\u00eda Emocional.<\/p><\/div><\/div><\/div><div class=\"lc-gut-blog-post-interview__item lc-gut-blog-post-interview__question\"><div class=\"lc-gut-blog-post-interview__person-image-wrap\"><img decoding=\"async\" class=\"lc-gut-blog-post-interview__person-image\" src=\"\/wp-content\/uploads\/2025\/08\/3f55c099cde3bffdfd03be0c9d50584e1a131ba7.png\" alt=\"Question Person\" \/><\/div><div class=\"lc-gut-blog-post-interview__content\"><div class=\"question\"><h3 class=\"lc-gut-blog-post-interview__question\"><strong>\u00bfQu\u00e9 ventajas ofrece ecox a un franquiciado?<\/strong><\/h3><\/div><\/div><\/div><div class=\"lc-gut-blog-post-interview__item lc-gut-blog-post-interview__answer\"><div class=\"lc-gut-blog-post-interview__content\"><div class=\"answer\"><p class=\"lc-gut-blog-post-interview__answer\"><strong>Abelardo Mart\u00ednez<\/strong>: Modelo probado, que funciona, con la mejor imagen hiperrealista 8k, con <strong>inteligencia artificial avanzada<\/strong>, con una <strong>baja inversi\u00f3n y alta rentabilidad<\/strong> con acuerdos comerciales con las principales marcas del sector como Quir\u00f3n Salud o Sanitas, ofreciendo ayudas a la financiaci\u00f3n y ec\u00f3grafo en alquiler.<\/p><\/div><\/div><\/div><div class=\"lc-gut-blog-post-interview__item lc-gut-blog-post-interview__question\"><div class=\"lc-gut-blog-post-interview__person-image-wrap\"><img decoding=\"async\" class=\"lc-gut-blog-post-interview__person-image\" src=\"\/wp-content\/uploads\/2025\/08\/3f55c099cde3bffdfd03be0c9d50584e1a131ba7.png\" alt=\"Question Person\" \/><\/div><div class=\"lc-gut-blog-post-interview__content\"><div class=\"question\"><h3 class=\"lc-gut-blog-post-interview__question\"><strong>\u00bfCu\u00e1l es el proceso t\u00edpico desde que un emprendedor muestra inter\u00e9s hasta que abre su local ecox?<\/strong><\/h3><\/div><\/div><\/div><div class=\"lc-gut-blog-post-interview__item lc-gut-blog-post-interview__answer\"><div class=\"lc-gut-blog-post-interview__content\"><div class=\"answer\"><p class=\"lc-gut-blog-post-interview__answer\"><strong>Abelardo Mart\u00ednez<\/strong>: Asesoramos intensamente durante todo el proceso, desde la zona de exclusividad, selecci\u00f3n de la ubicaci\u00f3n, planos, dise\u00f1o, proyecto decoraci\u00f3n e instalaciones, formaci\u00f3n te\u00f3rica y pr\u00e1ctica con embarazadas reales, y \u201cpuesta en marcha\u201d del negocio por personal de Central ecox.<\/p><\/div><\/div><\/div><\/div><\/div>\n\n<div class=\"lf-gut-blog-post-cta-efference\" style=\"border-color: var(--primary);\"><div class=\"lf-gut-blog-post-cta-efference__icon\" style=\"color: var(--primary);\"><svg class=\"icon-thumb-up\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"35\" height=\"35\" viewBox=\"0 0 48 48\" fill=\"none\" style=\"color: var(--primary);\"><path fill=\"currentColor\" d=\"M21.4998 4.89989L20.8499 4.13985L20.8474 4.14202L21.4998 4.89989ZM26.5397 4.89989L27.1922 4.14197L27.1842 4.13526L26.5397 4.89989ZM29.6998 7.62011L30.3547 6.86441L30.3522 6.86223L29.6998 7.62011ZM40.4197 18.3401L41.1776 17.6877L41.1754 17.6851L40.4197 18.3401ZM43.1398 21.5L43.8998 20.8501L43.8977 20.8476L43.1398 21.5ZM43.1398 26.54L43.8977 27.1924L43.9044 27.1845L43.1398 26.54ZM40.4197 29.6999L41.1754 30.3549L41.1776 30.3523L40.4197 29.6999ZM29.6998 40.4199L30.3521 41.1778L30.3547 41.1756L29.6998 40.4199ZM26.5397 43.1399L27.1896 43.8999L27.1921 43.8978L26.5397 43.1399ZM21.4998 43.1399L20.8474 43.8978L20.8553 43.9045L21.4998 43.1399ZM18.3398 40.4199L17.6849 41.1756L17.6874 41.1778L18.3398 40.4199ZM7.57978 29.6999L8.34803 29.0597L8.34206 29.0527L7.57978 29.6999ZM4.87977 26.52L4.11427 27.1635L4.11748 27.1672L4.87977 26.52ZM4.87977 21.52L4.11747 20.8728L4.11428 20.8766L4.87977 21.52ZM7.57978 18.3401L8.3421 18.9873L8.348 18.9803L7.57978 18.3401ZM18.3398 7.62011L17.6874 6.86223L17.6849 6.86442L18.3398 7.62011ZM22.6797 31.88L23.3869 31.1729L23.3416 31.1276L23.291 31.0886L22.6797 31.88ZM30.6198 30.4801L29.6694 30.1688L29.6583 30.2028L29.6496 30.2375L30.6198 30.4801ZM32.8597 23.64L31.917 23.3064L31.9131 23.3175L31.9094 23.3288L32.8597 23.64ZM26.3998 20.0802L25.4113 19.9286L25.4089 19.9442L25.407 19.9598L26.3998 20.0802ZM26.8597 17.0802L25.8819 16.8706L25.8758 16.8995L25.8713 16.9286L26.8597 17.0802ZM25.6398 15.0201L25.2859 15.9554L25.3046 15.9625L25.3235 15.9688L25.6398 15.0201ZM23.5798 15.68L22.7523 15.1185L22.7504 15.1213L23.5798 15.68ZM22.1496 5.65993C23.1528 4.80216 24.8649 4.79607 25.8953 5.66452L27.1842 4.13526C25.4146 2.64371 22.6067 2.63762 20.8499 4.13986L22.1496 5.65993ZM25.8873 5.65777L29.0474 8.37799L30.3522 6.86223L27.1921 4.14201L25.8873 5.65777ZM29.0448 8.3758C29.4608 8.73632 30.0056 9.02413 30.5348 9.22184C31.064 9.41956 31.6657 9.56005 32.2197 9.56005V7.56005C31.9738 7.56005 31.6155 7.49056 31.2347 7.34832C30.8539 7.20605 30.5387 7.0239 30.3547 6.86442L29.0448 8.3758ZM32.2197 9.56005H35.6198V7.56005H32.2197V9.56005ZM35.6198 9.56005C37.1875 9.56005 38.4797 10.8522 38.4797 12.4199H40.4797C40.4797 9.74759 38.292 7.56005 35.6198 7.56005V9.56005ZM38.4797 12.4199V15.8201H40.4797V12.4199H38.4797ZM38.4797 15.8201C38.4797 16.3655 38.6209 16.9672 38.8174 17.4959C39.0139 18.0247 39.3014 18.5765 39.6641 18.995L41.1754 17.6851C41.0181 17.5036 40.8356 17.1854 40.6921 16.7993C40.5486 16.4129 40.4797 16.0547 40.4797 15.8201H38.4797ZM39.6619 18.9925L42.3819 22.1524L43.8977 20.8476L41.1776 17.6877L39.6619 18.9925ZM42.3797 22.1499C43.2375 23.153 43.2436 24.8652 42.3751 25.8956L43.9044 27.1845C45.396 25.4149 45.402 22.607 43.8998 20.8501L42.3797 22.1499ZM42.3819 25.8876L39.6619 29.0476L41.1776 30.3523L43.8977 27.1924L42.3819 25.8876ZM39.6641 29.045C39.3035 29.461 39.0157 30.0058 38.818 30.535C38.6203 31.0642 38.4797 31.6659 38.4797 32.22H40.4797C40.4797 31.974 40.5492 31.6157 40.6915 31.2349C40.8338 30.8541 41.0159 30.5389 41.1754 30.3549L39.6641 29.045ZM38.4797 32.22V35.6201H40.4797V32.22H38.4797ZM38.4797 35.6201C38.4797 37.1878 37.1875 38.48 35.6198 38.48V40.48C38.292 40.48 40.4797 38.2924 40.4797 35.6201H38.4797ZM35.6198 38.48H32.2197V40.48H35.6198V38.48ZM32.2197 38.48C31.6744 38.48 31.0726 38.6211 30.544 38.8176C30.0152 39.014 29.4633 39.3015 29.0448 39.6642L30.3547 41.1756C30.5362 41.0183 30.8544 40.8358 31.2405 40.6923C31.6269 40.5488 31.9851 40.48 32.2197 40.48V38.48ZM29.0474 39.662L25.8874 42.382L27.1921 43.8978L30.3521 41.1778L29.0474 39.662ZM25.8899 42.3798C24.8867 43.2376 23.1746 43.2437 22.1442 42.3753L20.8553 43.9045C22.6249 45.3961 25.4328 45.4021 27.1896 43.8999L25.8899 42.3798ZM22.1521 42.382L18.9922 39.662L17.6874 41.1778L20.8474 43.8978L22.1521 42.382ZM18.9947 39.6642C18.5787 39.3037 18.0339 39.0159 17.5047 38.8182C16.9755 38.6205 16.3738 38.48 15.8198 38.48V40.48C16.0657 40.48 16.4241 40.5495 16.8048 40.6917C17.1856 40.834 17.5008 41.0161 17.6849 41.1756L18.9947 39.6642ZM15.8198 38.48H12.3597V40.48H15.8198V38.48ZM12.3597 38.48C10.792 38.48 9.49976 37.1878 9.49976 35.6201H7.49976C7.49976 38.2924 9.6875 40.48 12.3597 40.48V38.48ZM9.49976 35.6201V32.1999H7.49976V35.6201H9.49976ZM9.49976 32.1999C9.49976 31.6539 9.35826 31.0572 9.16508 30.5353C8.9714 30.0121 8.69178 29.4723 8.348 29.0598L6.81156 30.3401C6.96777 30.5276 7.14815 30.8478 7.28945 31.2296C7.43127 31.6127 7.49976 31.966 7.49976 32.1999H9.49976ZM8.34206 29.0527L5.64205 25.8728L4.11748 27.1672L6.81749 30.3472L8.34206 29.0527ZM5.64525 25.8766C4.79794 24.8685 4.79794 23.1715 5.64525 22.1635L4.11428 20.8766C2.64159 22.6285 2.64159 25.4115 4.11428 27.1635L5.64525 25.8766ZM5.64205 22.1672L8.34206 18.9873L6.81749 17.6928L4.11748 20.8728L5.64205 22.1672ZM8.348 18.9803C8.69178 18.5677 8.9714 18.028 9.16508 17.5047C9.35826 16.9828 9.49976 16.3861 9.49976 15.8401H7.49976C7.49976 16.074 7.43127 16.4273 7.28945 16.8104C7.14815 17.1922 6.96777 17.5124 6.81156 17.6999L8.348 18.9803ZM9.49976 15.8401V12.4199H7.49976V15.8401H9.49976ZM9.49976 12.4199C9.49976 10.8522 10.792 9.56005 12.3597 9.56005V7.56005C9.6875 7.56005 7.49976 9.74759 7.49976 12.4199H9.49976ZM12.3597 9.56005H15.8198V7.56005H12.3597V9.56005ZM15.8198 9.56005C16.3651 9.56005 16.9669 9.4189 17.4956 9.22247C18.0244 9.02599 18.5762 8.7385 18.9947 8.3758L17.6849 6.86442C17.5034 7.02171 17.1852 7.2042 16.799 7.34769C16.4127 7.49123 16.0544 7.56005 15.8198 7.56005V9.56005ZM18.9922 8.37798L22.1522 5.65777L20.8474 4.14202L17.6874 6.86224L18.9922 8.37798ZM19.1685 30.4314L22.0685 32.6714L23.291 31.0886L20.3911 28.8486L19.1685 30.4314ZM21.9726 32.5871C22.3408 32.9552 22.8395 33.1544 23.2304 33.2648C23.645 33.3819 24.0864 33.44 24.4598 33.44V31.44C24.2731 31.44 24.0145 31.4081 23.7741 31.3401C23.6565 31.3069 23.5592 31.2695 23.4859 31.233C23.4093 31.1948 23.3839 31.1699 23.3869 31.1729L21.9726 32.5871ZM24.4598 33.44H27.9998V31.44H24.4598V33.44ZM27.9998 33.44C28.799 33.44 29.5865 33.1456 30.2139 32.6881C30.842 32.2301 31.3818 31.5549 31.5899 30.7226L29.6496 30.2375C29.5777 30.5252 29.3675 30.83 29.0356 31.072C28.7031 31.3145 28.3205 31.44 27.9998 31.44V33.44ZM31.5701 30.7913L33.8101 23.9512L31.9094 23.3288L29.6694 30.1688L31.5701 30.7913ZM33.8025 23.9735C34.1312 23.0445 34.0165 22.0828 33.4742 21.3419C32.9352 20.6053 32.0571 20.2 31.0798 20.2V22.2C31.5024 22.2 31.7444 22.3647 31.8603 22.5231C31.973 22.6772 32.0483 22.9354 31.917 23.3064L33.8025 23.9735ZM31.0798 20.2H27.3398V22.2H31.0798V20.2ZM27.3398 20.2C27.3373 20.2 27.3416 20.1997 27.3504 20.2035C27.359 20.2074 27.3692 20.2142 27.3782 20.2243C27.3876 20.235 27.3914 20.2444 27.3923 20.2472C27.3932 20.2503 27.3881 20.2367 27.3925 20.2005L25.407 19.9598C25.2548 21.2156 26.1799 22.2 27.3398 22.2V20.2ZM27.3882 20.2317L27.8482 17.2317L25.8713 16.9286L25.4113 19.9286L27.3882 20.2317ZM27.8375 17.2897C28.1304 15.9229 27.2511 14.5031 25.956 14.0714L25.3235 15.9688C25.7084 16.0971 25.949 16.5575 25.8819 16.8706L27.8375 17.2897ZM25.9937 14.0848C25.3555 13.8433 24.6881 13.9027 24.1473 14.0902C23.612 14.2757 23.0868 14.6256 22.7523 15.1185L24.4072 16.2415C24.4528 16.1744 24.5875 16.0543 24.8023 15.9799C25.0114 15.9074 25.1841 15.9169 25.2859 15.9554L25.9937 14.0848ZM22.7504 15.1213L18.9104 20.8212L20.5691 21.9387L24.4091 16.2387L22.7504 15.1213ZM15.9998 29.6399V20.48H13.9998V29.6399H15.9998ZM15.9998 20.48C15.9998 20.2144 16.0287 20.0485 16.0604 19.9495C16.0888 19.8605 16.1152 19.837 16.121 19.8316C16.1424 19.812 16.2914 19.7 16.8798 19.7V17.7C16.1482 17.7 15.3571 17.8179 14.7685 18.3583C14.1585 18.9183 13.9998 19.7102 13.9998 20.48H15.9998ZM16.8798 19.7H17.8198V17.7H16.8798V19.7ZM17.8198 19.7C18.3941 19.7 18.5477 19.8104 18.574 19.8344C18.5776 19.8376 18.6998 19.9386 18.6998 20.48H20.6998C20.6998 19.7014 20.532 18.9123 19.9205 18.3556C19.3318 17.8195 18.5455 17.7 17.8198 17.7V19.7ZM18.6998 20.48V29.6399H20.6998V20.48H18.6998ZM18.6998 29.6399C18.6998 30.1755 18.5805 30.2788 18.5752 30.2838C18.5511 30.3061 18.3996 30.4199 17.8198 30.4199V32.4199C18.56 32.4199 19.3484 32.2937 19.9343 31.751C20.539 31.191 20.6998 30.4043 20.6998 29.6399H18.6998ZM17.8198 30.4199H16.8798V32.4199H17.8198V30.4199ZM16.8798 30.4199C16.2914 30.4199 16.1424 30.3079 16.121 30.2883C16.1152 30.2829 16.0888 30.2593 16.0604 30.1704C16.0287 30.0714 15.9998 29.9055 15.9998 29.6399H13.9998C13.9998 30.4097 14.1585 31.2015 14.7685 31.7616C15.3571 32.302 16.1482 32.4199 16.8798 32.4199V30.4199Z\"\/><\/svg><\/div><span class=\"lf-gut-blog-post-cta-efference__title lf-transform-none\">LEER TAMBI\u00c9N<\/span><div class=\"lf-gut-blog-post-cta-efference__lede\">\n<div class=\"wp-block-lexpress-highlighted-text-v2 lf-gut-blog-post-cta-efference__lede\">\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/lexpress-franchise.com\/es\/articulos\/abrir-una-franquicia-por-menos-de-10-000-euros-de-canon-de-entrada\/\">Abrir una franquicia por menos de 10.000 euros de canon de entrada<\/a><\/li>\n<\/ul>\n<\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"840\" height=\"1120\" src=\"https:\/\/lexpress-franchise.com\/wp-content\/uploads\/2026\/01\/pareja-con-imagen-bebe-en-ecox.png\" alt=\"pareja con imagen beb\u00e9 en ecox\" class=\"wp-image-1528911\" style=\"width:422px;height:auto\" srcset=\"https:\/\/lexpress-franchise.com\/wp-content\/uploads\/2026\/01\/pareja-con-imagen-bebe-en-ecox.png 840w, https:\/\/lexpress-franchise.com\/wp-content\/uploads\/2026\/01\/pareja-con-imagen-bebe-en-ecox-768x1024.png 768w, https:\/\/lexpress-franchise.com\/wp-content\/uploads\/2026\/01\/pareja-con-imagen-bebe-en-ecox-360x480.png 360w, https:\/\/lexpress-franchise.com\/wp-content\/uploads\/2026\/01\/pareja-con-imagen-bebe-en-ecox-480x640.png 480w, https:\/\/lexpress-franchise.com\/wp-content\/uploads\/2026\/01\/pareja-con-imagen-bebe-en-ecox-640x853.png 640w\" sizes=\"auto, (max-width: 840px) 100vw, 840px\" \/><\/figure>\n<\/div>\n\n<div class=\"lc-gut-blog-post-interview\" style=\"--color: #e74c3c;\"><div class=\"lc-gut-blog-post-interview__qa\"><div class=\"lc-gut-blog-post-interview__item lc-gut-blog-post-interview__question\"><div class=\"lc-gut-blog-post-interview__person-image-wrap\"><img decoding=\"async\" class=\"lc-gut-blog-post-interview__person-image\" src=\"\/wp-content\/uploads\/2025\/08\/3f55c099cde3bffdfd03be0c9d50584e1a131ba7.png\" alt=\"Question Person\" \/><\/div><div class=\"lc-gut-blog-post-interview__content\"><div class=\"question\"><h3 class=\"lc-gut-blog-post-interview__question\"><strong>\u00bfQu\u00e9 recursos tecnol\u00f3gicos y de actualizaci\u00f3n continua reciben las franquicias ecox?<\/strong><\/h3><\/div><\/div><\/div><div class=\"lc-gut-blog-post-interview__item lc-gut-blog-post-interview__answer\"><div class=\"lc-gut-blog-post-interview__content\"><div class=\"answer\"><p class=\"lc-gut-blog-post-interview__answer\"> <strong>Abelardo Mart\u00ednez<\/strong>: Una vez abierto el local, continuamos con formaci\u00f3n y apoyo permanente para las nuevas tecnolog\u00edas y <strong>campa\u00f1as de marketing<\/strong>.<\/p><\/div><\/div><\/div><div class=\"lc-gut-blog-post-interview__item lc-gut-blog-post-interview__question\"><div class=\"lc-gut-blog-post-interview__person-image-wrap\"><img decoding=\"async\" class=\"lc-gut-blog-post-interview__person-image\" src=\"\/wp-content\/uploads\/2025\/08\/3f55c099cde3bffdfd03be0c9d50584e1a131ba7.png\" alt=\"Question Person\" \/><\/div><div class=\"lc-gut-blog-post-interview__content\"><div class=\"question\"><h3 class=\"lc-gut-blog-post-interview__question\"><strong>\u00bfQu\u00e9 expectativas de retorno de inversi\u00f3n y rentabilidad propone ecox a sus franquiciados?<\/strong><\/h3><\/div><\/div><\/div><div class=\"lc-gut-blog-post-interview__item lc-gut-blog-post-interview__answer\"><div class=\"lc-gut-blog-post-interview__content\"><div class=\"answer\"><p class=\"lc-gut-blog-post-interview__answer\"><strong>Abelardo Mart\u00ednez<\/strong>: Somos muy serios con las expectativas econ\u00f3micas, cada proyecto es independiente y tiene sus propias caracter\u00edsticas, analizamos el mercado de forma conjunta con el emprendedor y pedimos la implicaci\u00f3n de los emprendedores desde el primer momento.<\/p><\/div><\/div><\/div><div class=\"lc-gut-blog-post-interview__item lc-gut-blog-post-interview__question\"><div class=\"lc-gut-blog-post-interview__person-image-wrap\"><img decoding=\"async\" class=\"lc-gut-blog-post-interview__person-image\" src=\"\/wp-content\/uploads\/2025\/08\/3f55c099cde3bffdfd03be0c9d50584e1a131ba7.png\" alt=\"Question Person\" \/><\/div><div class=\"lc-gut-blog-post-interview__content\"><div class=\"question\"><h3 class=\"lc-gut-blog-post-interview__question\"><strong>\u00bfC\u00f3mo describir\u00eda el estado actual de su sector en Espa\u00f1a?<\/strong><\/h3><\/div><\/div><\/div><div class=\"lc-gut-blog-post-interview__item lc-gut-blog-post-interview__answer\"><div class=\"lc-gut-blog-post-interview__content\"><div class=\"answer\"><p class=\"lc-gut-blog-post-interview__answer\"><strong>Abelardo Mart\u00ednez<\/strong>: Mercado muy influenciado por las nuevas tecnolog\u00edas, con una evoluci\u00f3n ascendente.<\/p><\/div><\/div><\/div><div class=\"lc-gut-blog-post-interview__item lc-gut-blog-post-interview__question\"><div class=\"lc-gut-blog-post-interview__person-image-wrap\"><img decoding=\"async\" class=\"lc-gut-blog-post-interview__person-image\" src=\"\/wp-content\/uploads\/2025\/08\/3f55c099cde3bffdfd03be0c9d50584e1a131ba7.png\" alt=\"Question Person\" \/><\/div><div class=\"lc-gut-blog-post-interview__content\"><div class=\"question\"><h3 class=\"lc-gut-blog-post-interview__question\"><strong>\u00bfCu\u00e1ntas franquicias tiene previsto abrir ecox en los pr\u00f3ximos 3-5 a\u00f1os?\u00a0<\/strong><\/h3><\/div><\/div><\/div><div class=\"lc-gut-blog-post-interview__item lc-gut-blog-post-interview__answer\"><div class=\"lc-gut-blog-post-interview__content\"><div class=\"answer\"><p class=\"lc-gut-blog-post-interview__answer\"><strong>Abelardo Mart\u00ednez<\/strong>: Nuestra previsi\u00f3n de crecimiento a 3 a\u00f1os es una <strong>horquilla de 30 a 40 nuevos centros<\/strong>.<\/p><\/div><\/div><\/div><div class=\"lc-gut-blog-post-interview__item lc-gut-blog-post-interview__question\"><div class=\"lc-gut-blog-post-interview__person-image-wrap\"><img decoding=\"async\" class=\"lc-gut-blog-post-interview__person-image\" src=\"\/wp-content\/uploads\/2025\/08\/3f55c099cde3bffdfd03be0c9d50584e1a131ba7.png\" alt=\"Question Person\" \/><\/div><div class=\"lc-gut-blog-post-interview__content\"><div class=\"question\"><h3 class=\"lc-gut-blog-post-interview__question\"><strong>\u00bfQu\u00e9 ciudades son prioritarias para las pr\u00f3ximas aperturas de ecox?<\/strong><\/h3><\/div><\/div><\/div><div class=\"lc-gut-blog-post-interview__item lc-gut-blog-post-interview__answer\"><div class=\"lc-gut-blog-post-interview__content\"><div class=\"answer\"><p class=\"lc-gut-blog-post-interview__answer\"><strong>Abelardo Mart\u00ednez<\/strong>: Catalu\u00f1a, Comunidad Valenciana, Galicia, Santander, Zaragoza, Andaluc\u00eda y Comunidad de Madrid.<\/p><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>En esta entrevista, Abelardo Mart\u00ednez, responsable de expansi\u00f3n de ecox, nos cuenta c\u00f3mo funciona la red de franquicias de ecograf\u00edas emocionales, las ventajas para los franquiciados y su estrategia de crecimiento en Espa\u00f1a para los pr\u00f3ximos a\u00f1os. Ecox combina tecnolog\u00eda avanzada, formaci\u00f3n completa y un modelo probado de negocio con alta rentabilidad. \u00bfQu\u00e9 es ecox? [&hellip;]<\/p>\n","protected":false},"author":429,"featured_media":1528888,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_titles_title":"Ecox prev\u00e9 abrir hasta 40 nuevos centros en 3 a\u00f1os en Espa\u00f1a","_seopress_titles_desc":"Abelardo Mart\u00ednez, responsable de Expansi\u00f3n de ecox, explica el modelo y oportunidades de esta red de franquicias de ecograf\u00edas emocionales en 3D en Espa\u00f1a.","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"content-type":"","_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"1407491,1452802,248976,486770,132557,244389","_relevanssi_noindex_reason":"","footnotes":""},"categories":[893,1858,1860],"tags":[],"type-de-post":[2066],"class_list":["post-1528838","post","type-post","status-publish","format-standard","has-post-thumbnail","category-sectores","category-redes-de-franquicias","category-desarrollarse","type-de-post-articles-actualite"],"acf":[],"_links":{"self":[{"href":"https:\/\/lexpress-franchise.com\/es\/wp-json\/wp\/v2\/posts\/1528838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lexpress-franchise.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lexpress-franchise.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lexpress-franchise.com\/es\/wp-json\/wp\/v2\/users\/429"}],"replies":[{"embeddable":true,"href":"https:\/\/lexpress-franchise.com\/es\/wp-json\/wp\/v2\/comments?post=1528838"}],"version-history":[{"count":5,"href":"https:\/\/lexpress-franchise.com\/es\/wp-json\/wp\/v2\/posts\/1528838\/revisions"}],"predecessor-version":[{"id":1739291,"href":"https:\/\/lexpress-franchise.com\/es\/wp-json\/wp\/v2\/posts\/1528838\/revisions\/1739291"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lexpress-franchise.com\/es\/wp-json\/wp\/v2\/media\/1528888"}],"wp:attachment":[{"href":"https:\/\/lexpress-franchise.com\/es\/wp-json\/wp\/v2\/media?parent=1528838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lexpress-franchise.com\/es\/wp-json\/wp\/v2\/categories?post=1528838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lexpress-franchise.com\/es\/wp-json\/wp\/v2\/tags?post=1528838"},{"taxonomy":"type-de-post","embeddable":true,"href":"https:\/\/lexpress-franchise.com\/es\/wp-json\/wp\/v2\/type-de-post?post=1528838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}